{"id":304946,"date":"2024-09-10T12:51:11","date_gmt":"2024-09-10T12:51:11","guid":{"rendered":"https:\/\/clarivate.com\/life-sciences-healthcare\/?page_id=301427"},"modified":"2026-04-21T01:16:15","modified_gmt":"2026-04-21T01:16:15","slug":"consulting-services","status":"publish","type":"page","link":"https:\/\/clarivate.com\/life-sciences-healthcare\/ko\/consulting-services\/","title":{"rendered":"\uc0dd\uba85\uacfc\ud559\u00b7\ud5ec\uc2a4\ucf00\uc5b4 \ucee8\uc124\ud305 \uc11c\ube44\uc2a4"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_links_to":"","_links_to_type":0},"tags":[],"class_list":["post-304946","page","type-page","status-publish","hentry","clarivate-industry-life-sciences-and-healthcare"],"acf":[],"lang":"ko","translations":{"ko":304946,"en":301427,"ja":304945,"zh":304947},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"pll_sync_post":[],"_links":{"self":[{"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/pages\/304946","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/comments?post=304946"}],"version-history":[{"count":11,"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/pages\/304946\/revisions"}],"predecessor-version":[{"id":579214,"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/pages\/304946\/revisions\/579214"}],"wp:attachment":[{"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/media?parent=304946"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/tags?post=304946"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}