{"id":301431,"date":"2024-09-10T13:00:15","date_gmt":"2024-09-10T13:00:15","guid":{"rendered":"https:\/\/clarivate.com\/life-sciences-healthcare\/?page_id=301431"},"modified":"2026-04-01T11:32:45","modified_gmt":"2026-04-01T11:32:45","slug":"research-and-development-consulting","status":"publish","type":"page","link":"https:\/\/clarivate.com\/life-sciences-healthcare\/consulting-services\/research-and-development-consulting\/","title":{"rendered":"Research and development consulting"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":8,"featured_media":0,"parent":301427,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_links_to":"","_links_to_type":0},"tags":[],"class_list":["post-301431","page","type-page","status-publish","hentry"],"acf":[],"lang":"en","translations":{"en":301431,"ja":304952,"ko":304953,"zh":304954},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"pll_sync_post":{"en":true,"ja":true,"zh":true},"_links":{"self":[{"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/pages\/301431","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/comments?post=301431"}],"version-history":[{"count":12,"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/pages\/301431\/revisions"}],"predecessor-version":[{"id":577853,"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/pages\/301431\/revisions\/577853"}],"up":[{"embeddable":true,"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/pages\/301427"}],"wp:attachment":[{"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/media?parent=301431"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/clarivate.com\/life-sciences-healthcare\/wp-json\/wp\/v2\/tags?post=301431"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}